{"id":9154,"date":"2024-09-27T09:14:54","date_gmt":"2024-09-27T07:14:54","guid":{"rendered":"https:\/\/novital.it\/covatutto-16lfan-incubateur-comment-incuber-des-oeufs-de-poule\/"},"modified":"2026-02-11T11:45:33","modified_gmt":"2026-02-11T10:45:33","slug":"covatutto-16lfan-incubateur-comment-incuber-des-oeufs-de-poule","status":"publish","type":"post","link":"https:\/\/novital.it\/fr\/covatutto-16lfan-incubateur-comment-incuber-des-oeufs-de-poule\/","title":{"rendered":"Couveuse Covatutto 16LFAN \u2013 Comment incuber des \u0153ufs de poule"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/novital.it\/wp-content\/uploads\/incubazione-di-successo-0-1-1200x800.jpg\" alt=\"Guide d&#x2019;incubation artificielle\" class=\"wp-image-17530\" srcset=\"https:\/\/novital.it\/wp-content\/uploads\/incubazione-di-successo-0-1-1200x800.jpg 1200w, https:\/\/novital.it\/wp-content\/uploads\/incubazione-di-successo-0-1-500x333.jpg 500w, https:\/\/novital.it\/wp-content\/uploads\/incubazione-di-successo-0-1-300x200.jpg 300w, https:\/\/novital.it\/wp-content\/uploads\/incubazione-di-successo-0-1-768x512.jpg 768w, https:\/\/novital.it\/wp-content\/uploads\/incubazione-di-successo-0-1-113x75.jpg 113w, https:\/\/novital.it\/wp-content\/uploads\/incubazione-di-successo-0-1-480x320.jpg 480w, https:\/\/novital.it\/wp-content\/uploads\/incubazione-di-successo-0-1-750x500.jpg 750w\" sizes=\"auto, (max-width:767px) 480px, (max-width:1200px) 100vw, 1200px\" \/><\/figure>\n<\/div>\n<p class=\"has-text-align-center wp-block-paragraph\">.<\/p>\n\n<p class=\"wp-block-paragraph\">L&rsquo;incubateur Covatutto 16LFAN est le nouvel incubateur puissant et compact de la maison Novital, qui marque un tournant pour ce type de mod\u00e8les. Il abandonne en effet le syst\u00e8me de chauffage par rayonnement, devenant ainsi le premier mod\u00e8le ventil\u00e9 de la s\u00e9rie 16L, dans lequel la temp\u00e9rature interne est maintenue gr\u00e2ce \u00e0 une r\u00e9sistance chauffante de 40 watts. <\/p>\n\n<p class=\"wp-block-paragraph\">Lors du montage, n&rsquo;oubliez pas qu&rsquo;il est important de laisser le cylindre de mat\u00e9riau isolant \u00e0 l&rsquo;int\u00e9rieur de la partie sup\u00e9rieure du corps de la machine. Pour l&rsquo;assemblage, vissez d&rsquo;abord l&rsquo;\u00e9crou de la bague dent\u00e9e sur la partie inf\u00e9rieure de la partie sup\u00e9rieure du corps de la machine, puis fixez-les par le bas avec les \u00e9crous appropri\u00e9s. Positionnez le levier de rotation sur le pivot central et placez la plaque basculante du retourneur d&rsquo;\u0153ufs sur celui-ci. Deux s\u00e9parateurs suppl\u00e9mentaires sont disponibles pour diviser le fond du retourneur d&rsquo;\u0153ufs en diff\u00e9rents secteurs.   <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"780\" src=\"https:\/\/novital.it\/wp-content\/uploads\/covatutto16l-fan-3.jpg\" alt=\"\" class=\"wp-image-18724\" srcset=\"https:\/\/novital.it\/wp-content\/uploads\/covatutto16l-fan-3.jpg 750w, https:\/\/novital.it\/wp-content\/uploads\/covatutto16l-fan-3-481x500.jpg 481w, https:\/\/novital.it\/wp-content\/uploads\/covatutto16l-fan-3-288x300.jpg 288w, https:\/\/novital.it\/wp-content\/uploads\/covatutto16l-fan-3-72x75.jpg 72w, https:\/\/novital.it\/wp-content\/uploads\/covatutto16l-fan-3-480x499.jpg 480w\" sizes=\"auto, (max-width:767px) 480px, 750px\" \/><figcaption class=\"wp-element-caption\">.<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Nous pouvons donc ins\u00e9rer les \u0153ufs \u00e0 l&rsquo;horizontale, en utilisant \u00e9ventuellement les s\u00e9parateurs pour d\u00e9limiter l&rsquo;espace dans lequel ils devront rester. Le Covatutto 16L FAN permet d&rsquo;incuber jusqu&rsquo;\u00e0 15-16 \u0153ufs de petite taille, ou un nombre moindre d&rsquo;\u0153ufs plus gros.  Positionnons le couvercle et relions avec le c\u00e2ble appropri\u00e9 le retourne-\u0153ufs, dans ce mod\u00e8le positionn\u00e9 en bas, avec la coupole de la machine. Une fois la prise branch\u00e9e sur une prise de courant, la machine commencera imm\u00e9diatement \u00e0 porter la temp\u00e9rature interne \u00e0 la valeur souhait\u00e9e.  Pour r\u00e9gler la temp\u00e9rature et la dur\u00e9e d&rsquo;incubation, nous agirons sur les touches \u00e0 droite de l&rsquo;\u00e9cran num\u00e9rique de la coupole : touche sup\u00e9rieure pour la temp\u00e9rature, touche inf\u00e9rieure pour la dur\u00e9e d&rsquo;incubation. Les valeurs \u00e0 r\u00e9gler pour l&rsquo;incubation d&rsquo;\u0153ufs de poule sont une temp\u00e9rature de 37,8 \u00b0C et une dur\u00e9e d&rsquo;incubation de 21 jours. La touche en bas \u00e0 gauche permet d&rsquo;allumer et d&rsquo;\u00e9teindre \u00e0 volont\u00e9 le retourne-\u0153ufs.   Ce dernier s&rsquo;allume pendant environ 40 secondes toutes les 90 minutes, pour garantir un d\u00e9placement optimal de l&rsquo;axe des \u0153ufs au cours de la journ\u00e9e. La machine est dot\u00e9e d&rsquo;une pr\u00e9disposition pour l&rsquo;utilisation du <strong><a href=\"https:\/\/novital.it\/fr\/produit\/thermohygrometre-numerique\/\">thermohygrom\u00e8tre num\u00e9rique Novital<\/a><\/strong>, non inclus dans l&rsquo;\u00e9quipement. <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"563\" src=\"https:\/\/novital.it\/wp-content\/uploads\/covatutto16l-fan-2-1.jpg\" alt=\"\" class=\"wp-image-18725\" srcset=\"https:\/\/novital.it\/wp-content\/uploads\/covatutto16l-fan-2-1.jpg 750w, https:\/\/novital.it\/wp-content\/uploads\/covatutto16l-fan-2-1-500x375.jpg 500w, https:\/\/novital.it\/wp-content\/uploads\/covatutto16l-fan-2-1-300x225.jpg 300w, https:\/\/novital.it\/wp-content\/uploads\/covatutto16l-fan-2-1-100x75.jpg 100w, https:\/\/novital.it\/wp-content\/uploads\/covatutto16l-fan-2-1-480x360.jpg 480w\" sizes=\"auto, (max-width:767px) 480px, 750px\" \/><figcaption class=\"wp-element-caption\">.<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Nous ajoutons ensuite de l&rsquo;eau dans le plateau 2 pour fournir l&rsquo;humidit\u00e9 n\u00e9cessaire pendant l&rsquo;incubation. \u00c0 3 jours de la fin de l&rsquo;incubation, la machine entre en phase d&rsquo;\u00e9closion et bloque le retourneur d&rsquo;\u0153ufs. Il faudra alors remplir \u00e9galement le deuxi\u00e8me plateau d&rsquo;eau, retirer le retourneur d&rsquo;\u0153ufs et le levier de rotation, et d\u00e9poser d\u00e9licatement les \u0153ufs sur la grille du fond. Une fois la couveuse ferm\u00e9e, vous ne l&rsquo;ouvrirez plus jusqu&rsquo;\u00e0 l&rsquo;\u00e9closion des poussins. Lorsque les poussins \u00e9closent, il faut les laisser dans la couveuse pendant 24 heures avant de les placer sous une lampe ou une poule artificielle.    <\/p>\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Incubatrice Covatutto 16LFAN:  come incubare le uova di gallina con la nuova incubatrice di Novital\" width=\"1220\" height=\"686\" src=\"https:\/\/www.youtube.com\/embed\/f2yrHBi_LgU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<p class=\"has-text-align-center wp-block-paragraph\">.<\/p>\n\n<p class=\"wp-block-paragraph\">Avec l&rsquo;incubateur Covatutto 16LFAN, il est possible d&rsquo;incuber tout type d&rsquo;\u0153ufs de volailles de basse-cour, en nombre adapt\u00e9 aux dimensions des \u0153ufs eux-m\u00eames. Cet incubateur petit et compact ne manquera pas de donner de grandes satisfactions aussi bien \u00e0 ceux qui s&rsquo;approchent pour la premi\u00e8re fois du monde de l&rsquo;Aviculture qu&rsquo;aux \u00e9leveurs les plus exp\u00e9riment\u00e9s ! Vous le trouverez sur notre <strong><a href=\"https:\/\/novital.it\/fr\/produit\/ventilateur-covatutto-16l\/\">boutique en ligne<\/a><\/strong>, avec de nombreux autres mod\u00e8les pour tous les besoins d&rsquo;incubation.   Bonne reproduction !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>. L&rsquo;incubateur Covatutto 16LFAN est le nouvel incubateur puissant et compact de la maison Novital, qui marque un tournant pour ce type de mod\u00e8les. Il abandonne<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":17532,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[257],"tags":[258,1308,301,261],"class_list":["post-9154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-incubateurs-et-accessoires","tag-incubateur","tag-incuber","tag-poussins","tag-oeufs"],"_links":{"self":[{"href":"https:\/\/novital.it\/fr\/wp-json\/wp\/v2\/posts\/9154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novital.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novital.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novital.it\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novital.it\/fr\/wp-json\/wp\/v2\/comments?post=9154"}],"version-history":[{"count":3,"href":"https:\/\/novital.it\/fr\/wp-json\/wp\/v2\/posts\/9154\/revisions"}],"predecessor-version":[{"id":18740,"href":"https:\/\/novital.it\/fr\/wp-json\/wp\/v2\/posts\/9154\/revisions\/18740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novital.it\/fr\/wp-json\/wp\/v2\/media\/17532"}],"wp:attachment":[{"href":"https:\/\/novital.it\/fr\/wp-json\/wp\/v2\/media?parent=9154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novital.it\/fr\/wp-json\/wp\/v2\/categories?post=9154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novital.it\/fr\/wp-json\/wp\/v2\/tags?post=9154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}